{"id":105150,"date":"2014-10-30T09:41:41","date_gmt":"2014-10-30T02:41:41","guid":{"rendered":"http:\/\/www.flashfly.net\/wp\/wp-content\/uploads\/2014\/10\/screen480x4806.jpeg"},"modified":"2014-10-30T09:41:41","modified_gmt":"2014-10-30T02:41:41","slug":"screen480x480-105","status":"inherit","type":"attachment","link":"https:\/\/www.flashfly.net\/wp\/105144\/screen480x480-105","title":{"rendered":"screen480x480"},"author":1,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.flashfly.net\/wp\/wp-content\/uploads\/2014\/10\/screen480x4806.jpeg'><img decoding=\"async\" width=\"230\" height=\"130\" src=\"https:\/\/www.flashfly.net\/wp\/wp-content\/uploads\/2014\/10\/screen480x4806-230x130.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":480,"height":360,"file":"2014\/10\/screen480x4806.jpeg","sizes":{"thumbnail":{"file":"screen480x4806-110x110.jpeg","width":110,"height":110,"mime_type":"image\/jpeg","source_url":"https:\/\/www.flashfly.net\/wp\/wp-content\/uploads\/2014\/10\/screen480x4806-110x110.jpeg"},"medium":{"file":"screen480x4806-230x130.jpeg","width":230,"height":130,"mime_type":"image\/jpeg","source_url":"https:\/\/www.flashfly.net\/wp\/wp-content\/uploads\/2014\/10\/screen480x4806-230x130.jpeg"},"full":{"file":"screen480x4806.jpeg","width":480,"height":360,"mime_type":"image\/jpeg","source_url":"https:\/\/www.flashfly.net\/wp\/wp-content\/uploads\/2014\/10\/screen480x4806.jpeg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":""}},"post":105144,"source_url":"https:\/\/www.flashfly.net\/wp\/wp-content\/uploads\/2014\/10\/screen480x4806.jpeg","_links":{"self":[{"href":"https:\/\/www.flashfly.net\/wp\/wp-json\/wp\/v2\/media\/105150"}],"collection":[{"href":"https:\/\/www.flashfly.net\/wp\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.flashfly.net\/wp\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.flashfly.net\/wp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.flashfly.net\/wp\/wp-json\/wp\/v2\/comments?post=105150"}]}}