{"id":182611,"date":"2017-05-12T15:26:18","date_gmt":"2017-05-12T08:26:18","guid":{"rendered":"http:\/\/www.flashfly.net\/wp\/wp-content\/uploads\/2017\/05\/pes_02_action.jpg"},"modified":"2017-05-12T15:26:18","modified_gmt":"2017-05-12T08:26:18","slug":"pes_02_action","status":"inherit","type":"attachment","link":"https:\/\/www.flashfly.net\/wp\/182609\/pes_02_action","title":{"rendered":"pes_02_action"},"author":88189,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.flashfly.net\/wp\/wp-content\/uploads\/2017\/05\/pes_02_action.jpg'><img decoding=\"async\" width=\"230\" height=\"130\" src=\"https:\/\/www.flashfly.net\/wp\/wp-content\/uploads\/2017\/05\/pes_02_action-230x130.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"\/\/www.flashfly.net\/wp\/wp-content\/uploads\/2017\/05\/pes_02_action-230x130.jpg 230w, \/\/www.flashfly.net\/wp\/wp-content\/uploads\/2017\/05\/pes_02_action-640x360.jpg 640w, \/\/www.flashfly.net\/wp\/wp-content\/uploads\/2017\/05\/pes_02_action.jpg 700w\" sizes=\"(max-width: 230px) 100vw, 230px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":700,"height":394,"file":"2017\/05\/pes_02_action.jpg","sizes":{"thumbnail":{"file":"pes_02_action-110x110.jpg","width":110,"height":110,"mime_type":"image\/jpeg","source_url":"https:\/\/www.flashfly.net\/wp\/wp-content\/uploads\/2017\/05\/pes_02_action-110x110.jpg"},"medium":{"file":"pes_02_action-230x130.jpg","width":230,"height":130,"mime_type":"image\/jpeg","source_url":"https:\/\/www.flashfly.net\/wp\/wp-content\/uploads\/2017\/05\/pes_02_action-230x130.jpg"},"large":{"file":"pes_02_action-640x360.jpg","width":640,"height":360,"mime_type":"image\/jpeg","source_url":"https:\/\/www.flashfly.net\/wp\/wp-content\/uploads\/2017\/05\/pes_02_action-640x360.jpg"},"slider-thumb":{"file":"pes_02_action-520x394.jpg","width":520,"height":394,"mime_type":"image\/jpeg","source_url":"https:\/\/www.flashfly.net\/wp\/wp-content\/uploads\/2017\/05\/pes_02_action-520x394.jpg"},"full":{"file":"pes_02_action.jpg","width":700,"height":394,"mime_type":"image\/jpeg","source_url":"https:\/\/www.flashfly.net\/wp\/wp-content\/uploads\/2017\/05\/pes_02_action.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":""}},"post":182609,"source_url":"https:\/\/www.flashfly.net\/wp\/wp-content\/uploads\/2017\/05\/pes_02_action.jpg","_links":{"self":[{"href":"https:\/\/www.flashfly.net\/wp\/wp-json\/wp\/v2\/media\/182611"}],"collection":[{"href":"https:\/\/www.flashfly.net\/wp\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.flashfly.net\/wp\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.flashfly.net\/wp\/wp-json\/wp\/v2\/users\/88189"}],"replies":[{"embeddable":true,"href":"https:\/\/www.flashfly.net\/wp\/wp-json\/wp\/v2\/comments?post=182611"}]}}