{"id":222915,"date":"2018-07-07T00:21:22","date_gmt":"2018-07-06T17:21:22","guid":{"rendered":"http:\/\/www.flashfly.net\/wp\/wp-content\/uploads\/2018\/07\/concept-samsung-Beyond.jpg"},"modified":"2018-07-07T00:21:22","modified_gmt":"2018-07-06T17:21:22","slug":"concept-samsung-beyond","status":"inherit","type":"attachment","link":"https:\/\/www.flashfly.net\/wp\/222914\/concept-samsung-beyond","title":{"rendered":"concept-samsung-Beyond"},"author":88189,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.flashfly.net\/wp\/wp-content\/uploads\/2018\/07\/concept-samsung-Beyond.jpg'><img decoding=\"async\" width=\"300\" height=\"156\" src=\"https:\/\/www.flashfly.net\/wp\/wp-content\/uploads\/2018\/07\/concept-samsung-Beyond-300x156.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"\/\/www.flashfly.net\/wp\/wp-content\/uploads\/2018\/07\/concept-samsung-Beyond-300x156.jpg 300w, \/\/www.flashfly.net\/wp\/wp-content\/uploads\/2018\/07\/concept-samsung-Beyond-768x400.jpg 768w, \/\/www.flashfly.net\/wp\/wp-content\/uploads\/2018\/07\/concept-samsung-Beyond-800x417.jpg 800w, \/\/www.flashfly.net\/wp\/wp-content\/uploads\/2018\/07\/concept-samsung-Beyond-750x390.jpg 750w, \/\/www.flashfly.net\/wp\/wp-content\/uploads\/2018\/07\/concept-samsung-Beyond.jpg 968w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":968,"height":504,"file":"2018\/07\/concept-samsung-Beyond.jpg","sizes":{"thumbnail":{"file":"concept-samsung-Beyond-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.flashfly.net\/wp\/wp-content\/uploads\/2018\/07\/concept-samsung-Beyond-150x150.jpg"},"medium":{"file":"concept-samsung-Beyond-300x156.jpg","width":300,"height":156,"mime_type":"image\/jpeg","source_url":"https:\/\/www.flashfly.net\/wp\/wp-content\/uploads\/2018\/07\/concept-samsung-Beyond-300x156.jpg"},"medium_large":{"file":"concept-samsung-Beyond-768x400.jpg","width":768,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/www.flashfly.net\/wp\/wp-content\/uploads\/2018\/07\/concept-samsung-Beyond-768x400.jpg"},"large":{"file":"concept-samsung-Beyond-800x417.jpg","width":800,"height":417,"mime_type":"image\/jpeg","source_url":"https:\/\/www.flashfly.net\/wp\/wp-content\/uploads\/2018\/07\/concept-samsung-Beyond-800x417.jpg"},"jnews-360x180":{"file":"concept-samsung-Beyond-360x180.jpg","width":360,"height":180,"mime_type":"image\/jpeg","source_url":"https:\/\/www.flashfly.net\/wp\/wp-content\/uploads\/2018\/07\/concept-samsung-Beyond-360x180.jpg"},"jnews-750x375":{"file":"concept-samsung-Beyond-750x375.jpg","width":750,"height":375,"mime_type":"image\/jpeg","source_url":"https:\/\/www.flashfly.net\/wp\/wp-content\/uploads\/2018\/07\/concept-samsung-Beyond-750x375.jpg"},"jnews-120x86":{"file":"concept-samsung-Beyond-120x86.jpg","width":120,"height":86,"mime_type":"image\/jpeg","source_url":"https:\/\/www.flashfly.net\/wp\/wp-content\/uploads\/2018\/07\/concept-samsung-Beyond-120x86.jpg"},"jnews-350x250":{"file":"concept-samsung-Beyond-350x250.jpg","width":350,"height":250,"mime_type":"image\/jpeg","source_url":"https:\/\/www.flashfly.net\/wp\/wp-content\/uploads\/2018\/07\/concept-samsung-Beyond-350x250.jpg"},"jnews-750x536":{"file":"concept-samsung-Beyond-750x504.jpg","width":750,"height":504,"mime_type":"image\/jpeg","source_url":"https:\/\/www.flashfly.net\/wp\/wp-content\/uploads\/2018\/07\/concept-samsung-Beyond-750x504.jpg"},"jnews-360x504":{"file":"concept-samsung-Beyond-360x504.jpg","width":360,"height":504,"mime_type":"image\/jpeg","source_url":"https:\/\/www.flashfly.net\/wp\/wp-content\/uploads\/2018\/07\/concept-samsung-Beyond-360x504.jpg"},"jnews-75x75":{"file":"concept-samsung-Beyond-75x75.jpg","width":75,"height":75,"mime_type":"image\/jpeg","source_url":"https:\/\/www.flashfly.net\/wp\/wp-content\/uploads\/2018\/07\/concept-samsung-Beyond-75x75.jpg"},"jnews-featured-750":{"file":"concept-samsung-Beyond-750x390.jpg","width":750,"height":390,"mime_type":"image\/jpeg","source_url":"https:\/\/www.flashfly.net\/wp\/wp-content\/uploads\/2018\/07\/concept-samsung-Beyond-750x390.jpg"},"full":{"file":"concept-samsung-Beyond.jpg","width":968,"height":504,"mime_type":"image\/jpeg","source_url":"https:\/\/www.flashfly.net\/wp\/wp-content\/uploads\/2018\/07\/concept-samsung-Beyond.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":222914,"source_url":"https:\/\/www.flashfly.net\/wp\/wp-content\/uploads\/2018\/07\/concept-samsung-Beyond.jpg","_links":{"self":[{"href":"https:\/\/www.flashfly.net\/wp\/wp-json\/wp\/v2\/media\/222915"}],"collection":[{"href":"https:\/\/www.flashfly.net\/wp\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.flashfly.net\/wp\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.flashfly.net\/wp\/wp-json\/wp\/v2\/users\/88189"}],"replies":[{"embeddable":true,"href":"https:\/\/www.flashfly.net\/wp\/wp-json\/wp\/v2\/comments?post=222915"}]}}