{"id":126226,"date":"2015-08-21T16:24:27","date_gmt":"2015-08-21T09:24:27","guid":{"rendered":"http:\/\/www.flashfly.net\/wp\/?p=126226"},"modified":"2015-08-21T16:24:27","modified_gmt":"2015-08-21T09:24:27","slug":"%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94%e0%b9%81%e0%b8%a5%e0%b9%89%e0%b8%a7-%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b9%80%e0%b8%81%e0%b8%a1%e0%b8%a1%e0%b8%b7%e0%b8%ad%e0%b8%96%e0%b8%b7%e0%b8%ad%e0%b8%aa","status":"publish","type":"post","link":"https:\/\/www.flashfly.net\/wp\/126226","title":{"rendered":"\u0e40\u0e1b\u0e34\u0e14\u0e41\u0e25\u0e49\u0e27!! \u0e07\u0e32\u0e19\u0e40\u0e01\u0e21\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d\u0e2a\u0e38\u0e14\u0e22\u0e34\u0e48\u0e07\u0e43\u0e2b\u0e0d\u0e48\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e35 MOBILE GAME FEST &#038; DIGITAL LIFESTYLE 2015 \u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e16\u0e36\u0e07 23 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 \u0e13 \u0e23\u0e2d\u0e22\u0e31\u0e25 \u0e1e\u0e32\u0e23\u0e32\u0e01\u0e2d\u0e19 \u0e2e\u0e2d\u0e25\u0e25\u0e4c"},"content":{"rendered":"<p>\u0e23\u0e2d\u0e22\u0e31\u0e25 \u0e1e\u0e32\u0e23\u0e32\u0e01\u0e2d\u0e19\u0e2e\u0e2d\u0e25\u0e25\u0e4c \u0e1c\u0e19\u0e36\u0e01\u0e1e\u0e31\u0e19\u0e18\u0e21\u0e34\u0e15\u0e23\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 \u0e20\u0e32\u0e04\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e41\u0e25\u0e30\u0e04\u0e48\u0e32\u0e22\u0e40\u0e01\u0e21\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33<!--more--> \u0e42\u0e14\u0e22\u0e21\u0e35 ONLINE STATION \u0e22\u0e31\u0e01\u0e29\u0e4c\u0e43\u0e2b\u0e0d\u0e48\u0e41\u0e2b\u0e48\u0e07\u0e2a\u0e37\u0e48\u0e2d\u0e40\u0e01\u0e21\u0e02\u0e2d\u0e07\u0e44\u0e17\u0e22\u0e23\u0e48\u0e27\u0e21\u0e08\u0e38\u0e14\u0e01\u0e23\u0e30\u0e41\u0e2a\u0e07\u0e32\u0e19\u0e40\u0e01\u0e21\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d\u0e2a\u0e38\u0e14\u0e22\u0e34\u0e48\u0e07\u0e43\u0e2b\u0e0d\u0e48\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e35 MOBILE GAME FEST &amp; DIGITAL LIFESTYLE 2015 \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e04\u0e2d\u0e19\u0e40\u0e0b\u0e47\u0e1b\u0e15\u0e4c \u201cLIFE IS FUN \u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e19\u0e2a\u0e4c \u0e27\u0e31\u0e19\u0e40\u0e01\u0e21\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d\u201d \u0e22\u0e01\u0e17\u0e31\u0e1e\u0e40\u0e01\u0e21\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e44\u0e2d\u0e17\u0e35 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e40\u0e01\u0e21\u0e17\u0e35\u0e48\u0e21\u0e35\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e23\u0e48\u0e27\u0e21 3 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e40\u0e01\u0e21\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d\u0e2a\u0e39\u0e48\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e32\u0e01\u0e25 \u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e21\u0e35\u0e1c\u0e39\u0e49\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19\u0e01\u0e27\u0e48\u0e32 60,000 \u0e04\u0e19 \u0e15\u0e25\u0e2d\u0e14\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 21\u201323 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2558 \u0e13 \u0e23\u0e2d\u0e22\u0e31\u0e25 \u0e1e\u0e32\u0e23\u0e32\u0e01\u0e2d\u0e19 \u0e2e\u0e2d\u0e25\u0e25\u0e4c \u0e0a\u0e31\u0e49\u0e19 5 \u0e2a\u0e22\u0e32\u0e21\u0e1e\u0e32\u0e23\u0e32\u0e01\u0e2d\u0e19<\/p>\n<p><a href=\"http:\/\/www.flashfly.net\/wp\/?attachment_id=126229#main\" rel=\"attachment wp-att-126229\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-126229\" alt=\"008\" src=\"http:\/\/www.flashfly.net\/wp\/wp-content\/uploads\/2015\/08\/008.jpg\" width=\"1024\" height=\"683\" \/><\/a><\/p>\n<p>\u0e19\u0e32\u0e22\u0e17\u0e32\u0e25\u0e39\u0e19 \u0e40\u0e17\u0e07 \u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \u0e23\u0e2d\u0e22\u0e31\u0e25 \u0e1e\u0e32\u0e23\u0e32\u0e01\u0e2d\u0e19 \u0e2e\u0e2d\u0e25\u0e25\u0e4c \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e43\u0e2b\u0e21\u0e48\u0e46 \u0e17\u0e31\u0e49\u0e07\u0e40\u0e01\u0e21 \u0e41\u0e25\u0e30\u0e41\u0e2d\u0e1e\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19\u0e1a\u0e19\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d \u0e41\u0e25\u0e30\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a \u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e08\u0e36\u0e07\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e07\u0e32\u0e19 Mobile Game fest &amp; Digital Lifestyle 2015 \u0e02\u0e36\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e23\u0e2d\u0e22\u0e31\u0e25 \u0e1e\u0e32\u0e23\u0e32\u0e01\u0e2d\u0e19 \u0e2e\u0e2d\u0e25\u0e25\u0e4c \u0e42\u0e14\u0e22\u0e20\u0e32\u0e22\u0e43\u0e19\u0e07\u0e32\u0e19 \u0e17\u0e48\u0e32\u0e19\u0e08\u0e30\u0e44\u0e14\u0e49\u0e1e\u0e1a\u0e01\u0e31\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e08\u0e32\u0e01\u0e04\u0e48\u0e32\u0e22\u0e40\u0e01\u0e21\u0e0a\u0e37\u0e48\u0e2d\u0e14\u0e31\u0e07\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22 \u0e2d\u0e32\u0e17\u0e34<\/p>\n<p>\u2022 \u0e02\u0e1a\u0e27\u0e19\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e23\u0e32\u0e04\u0e32\u0e1e\u0e34\u0e40\u0e28\u0e29 \u0e41\u0e25\u0e30 \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e40\u0e01\u0e21\u0e08\u0e32\u0e01\u0e04\u0e48\u0e32\u0e22\u0e02\u0e2d\u0e07 Acer<br \/>\n\u2022 NHN \u0e44\u0e14\u0e49\u0e22\u0e01\u0e02\u0e1a\u0e27\u0e19\u0e40\u0e01\u0e21\u0e21\u0e32\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e04\u0e2d\u0e19\u0e40\u0e0b\u0e47\u0e1b\u0e15\u0e4c NHN WORLD<br \/>\n\u2022 Electronics Extreme\u0e40\u0e1b\u0e34\u0e14\u0e2a\u0e31\u0e07\u0e40\u0e27\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19 EXTREME SPORTS LEAGUE 2015 \u0e0b\u0e36\u0e48\u0e07\u0e08\u0e30\u0e21\u0e35\u0e22\u0e2d\u0e14\u0e1c\u0e39\u0e49\u0e40\u0e02\u0e49\u0e32\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e2a\u0e39\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e01\u0e27\u0e48\u0e32 5,000 \u0e0a\u0e35\u0e27\u0e34\u0e15<br \/>\n\u2022 \u0e21\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19 FPS Grand Tournament \u0e0a\u0e34\u0e07\u0e40\u0e07\u0e34\u0e19\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e23\u0e27\u0e21\u0e01\u0e27\u0e48\u0e32 600,000 \u0e1a\u0e32\u0e17 \u0e08\u0e32\u0e01 True Digital Plus<br \/>\n\u2022 \u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e15\u0e31\u0e27\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e17\u0e14\u0e25\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e27\u0e32\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e04\u0e23\u0e31\u0e49\u0e07\u0e41\u0e23\u0e01 \u0e01\u0e31\u0e1a \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c Samsung Gear VR\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e17\u0e32\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e2b\u0e21\u0e48\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e40\u0e01\u0e21\u0e40\u0e21\u0e2d\u0e23\u0e4c<\/p>\n<p><a href=\"http:\/\/www.flashfly.net\/wp\/?attachment_id=126227#main\" rel=\"attachment wp-att-126227\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-126227\" alt=\"030\" src=\"http:\/\/www.flashfly.net\/wp\/wp-content\/uploads\/2015\/08\/030.jpg\" width=\"1024\" height=\"683\" \/><\/a><\/p>\n<p>\u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e08\u0e34\u0e23\u0e31\u0e10\u0e15\u0e34\u0e01\u0e32\u0e25 \u0e2a\u0e38\u0e17\u0e18\u0e34\u0e27\u0e23\u0e23\u0e13\u0e32\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e1d\u0e48\u0e32\u0e22\u0e1e\u0e31\u0e1a\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e17\u0e23\u0e39 \u0e44\u0e2d\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e49\u0e19\u0e17\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u0e17\u0e23\u0e39 \u0e44\u0e2d\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e49\u0e19\u0e17\u0e4c \u0e42\u0e14\u0e22 ONLINE STATION \u0e40\u0e01\u0e21 \u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e40\u0e19\u0e47\u0e15\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e1e\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e19\u0e2d\u0e23\u0e4c (Media Partner) \u0e08\u0e31\u0e14\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e02\u0e48\u0e32\u0e27\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e20\u0e32\u0e22\u0e43\u0e19\u0e07\u0e32\u0e19 MOBILE GAME FEST &amp; DIGITAL LIFESTYLE 2015 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14\u0e41\u0e25\u0e30\u0e1b\u0e34\u0e14\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e15\u0e25\u0e2d\u0e14 3 \u0e27\u0e31\u0e19 \u0e42\u0e14\u0e22\u0e04\u0e2d\u0e40\u0e01\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e31\u0e1a\u0e0a\u0e21\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e04\u0e27\u0e32\u0e21\u0e15\u0e37\u0e48\u0e19\u0e15\u0e32\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e43\u0e19\u0e07\u0e32\u0e19 \u0e08\u0e32\u0e01\u0e2a\u0e37\u0e48\u0e2d\u0e43\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e17\u0e31\u0e49\u0e07 \u0e01\u0e32\u0e23\u0e2d\u0e31\u0e1e\u0e40\u0e14\u0e17\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e20\u0e32\u0e22\u0e43\u0e19\u0e07\u0e32\u0e19\u0e41\u0e1a\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e25\u0e44\u0e17\u0e21\u0e4c \u0e17\u0e32\u0e07\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e14\u0e4c ONLINE STATION \u0e17\u0e35\u0e48\u0e21\u0e35\u0e08\u0e33\u0e19\u0e27\u0e19\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e2110 \u0e25\u0e49\u0e32\u0e19 UIP \u0e15\u0e48\u0e2d\u0e1b\u0e35 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07 Facebook ONLINE STATION \u0e41\u0e25\u0e30 \u0e01\u0e32\u0e23\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e2a\u0e01\u0e39\u0e4a\u0e1b\u0e02\u0e48\u0e32\u0e27\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2b\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e17\u0e32\u0e07 ONLINE STATION CHANNEL \u0e1a\u0e19 YOUTUBE \u0e17\u0e35\u0e48\u0e21\u0e35\u0e22\u0e2d\u0e14\u0e1c\u0e39\u0e49\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e01\u0e27\u0e48\u0e32 100,000 \u0e04\u0e19 \u0e41\u0e25\u0e30\u0e17\u0e32\u0e07\u0e19\u0e34\u0e15\u0e22\u0e2a\u0e32\u0e23 Future Gamer, Play, Online Station \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e40\u0e0a\u0e34\u0e0d\u0e0a\u0e27\u0e19\u0e1c\u0e39\u0e49\u0e1b\u0e01\u0e04\u0e23\u0e2d\u0e07\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e0a\u0e21\u0e07\u0e32\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e01\u0e31\u0e1a\u0e2d\u0e32\u0e0a\u0e35\u0e1e \u201c\u0e41\u0e04\u0e2a\u0e40\u0e15\u0e2d\u0e23\u0e4c\u201d (\u0e19\u0e31\u0e01\u0e1e\u0e32\u0e01\u0e22\u0e4c\u0e40\u0e01\u0e21) \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u0e43\u0e2b\u0e21\u0e48\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e40\u0e14\u0e47\u0e01 \u0e46 \u0e17\u0e35\u0e48\u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e25\u0e48\u0e19\u0e40\u0e01\u0e21\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e2d\u0e32\u0e22\u0e38\u0e22\u0e31\u0e07\u0e19\u0e49\u0e2d\u0e22 \u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e41\u0e04\u0e2a\u0e40\u0e01\u0e21\u0e2a\u0e14\u0e1a\u0e19\u0e40\u0e27\u0e17\u0e35\u0e01\u0e25\u0e32\u0e07 \u0e0b\u0e36\u0e48\u0e07 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e17\u0e23\u0e39 \u0e44\u0e2d\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e49\u0e19\u0e17\u0e4c \u0e42\u0e14\u0e22 ONLINE STATION \u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e27\u0e48\u0e32 \u0e04\u0e27\u0e32\u0e21\u0e41\u0e02\u0e47\u0e07\u0e41\u0e01\u0e23\u0e48\u0e07\u0e2a\u0e37\u0e48\u0e2d\u0e40\u0e01\u0e21\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23\u0e17\u0e38\u0e01\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e08\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e44\u0e14\u0e49\u0e15\u0e23\u0e07\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21 \u0e41\u0e25\u0e30\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e0a\u0e48\u0e27\u0e22\u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19\u0e27\u0e07\u0e01\u0e32\u0e23\u0e40\u0e01\u0e21\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d\u0e43\u0e2b\u0e49\u0e01\u0e27\u0e49\u0e32\u0e07\u0e02\u0e27\u0e32\u0e07\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e32\u0e01\u0e25\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22<\/p>\n<p><a href=\"http:\/\/www.flashfly.net\/wp\/?attachment_id=126230#main\" rel=\"attachment wp-att-126230\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-126230\" alt=\"006\" src=\"http:\/\/www.flashfly.net\/wp\/wp-content\/uploads\/2015\/08\/006.jpg\" width=\"1024\" height=\"683\" \/><\/a><\/p>\n<p>\u0e1e\u0e25\u0e40\u0e2d\u0e01\u0e42\u0e2a\u0e20\u0e13 \u0e40\u0e27\u0e04\u0e30\u0e27\u0e32\u0e01\u0e22\u0e32\u0e19\u0e19\u0e17\u0e4c \u0e23\u0e31\u0e01\u0e29\u0e32\u0e01\u0e32\u0e23\u0e43\u0e19\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 \u0e2b\u0e23\u0e37\u0e2d SIPA \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e16\u0e36\u0e07\u0e43\u0e2b\u0e49\u0e17\u0e23\u0e32\u0e1a\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e15\u0e4c\u0e44\u0e17\u0e22 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e43\u0e2b\u0e49\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2a\u0e39\u0e48\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e2b\u0e23\u0e37\u0e2d Digital Economy \u0e41\u0e25\u0e30\u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19\u0e43\u0e2b\u0e49\u0e41\u0e2a\u0e14\u0e07\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e48\u0e2a\u0e32\u0e01\u0e25 \u0e0b\u0e36\u0e48\u0e07\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e02\u0e2d\u0e07\u0e0b\u0e34\u0e1b\u0e49\u0e32\u0e43\u0e19\u0e07\u0e32\u0e19\u0e19\u0e35\u0e49 \u0e41\u0e1a\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19 4 \u0e2a\u0e48\u0e27\u0e19 \u0e04\u0e37\u0e2d \u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23 TICTA Expo 2015 \u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e32\u0e15\u0e34\u0e08\u0e32\u0e01\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 Thailand ICT Awards, \u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14 Angel in the City 2015 \u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e21\u0e48\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1a\u0e48\u0e21\u0e40\u0e1e\u0e32\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e02\u0e2d\u0e07\u0e0b\u0e34\u0e1b\u0e49\u0e32,\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e41\u0e2a\u0e14\u0e07\u0e1c\u0e25\u0e07\u0e32\u0e19 Bangkok International Digital Content Festival (BIDC) \u201cDigital Content Showcase\u201d \u0e23\u0e27\u0e21\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e14\u0e49\u0e32\u0e19\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e15\u0e4c\u0e1d\u0e35\u0e21\u0e37\u0e2d\u0e04\u0e19\u0e44\u0e17\u0e22\u0e41\u0e25\u0e30 \u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23 ACM-ICPC\u0e41\u0e19\u0e30\u0e19\u0e33\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e40\u0e02\u0e35\u0e22\u0e19\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e42\u0e25\u0e01 ACM-International Collegiate Programming Contest \u0e42\u0e14\u0e22\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e31\u0e49\u0e07 4 \u0e2a\u0e48\u0e27\u0e19\u0e08\u0e30\u0e21\u0e35\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e04\u0e2d\u0e19\u0e40\u0e17\u0e19\u0e15\u0e4c\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e44\u0e21\u0e48\u0e15\u0e48\u0e33\u0e01\u0e27\u0e48\u0e32 120 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e14\u0e49\u0e27\u0e22\u0e01\u0e31\u0e19<\/p>\n<p><a href=\"http:\/\/www.flashfly.net\/wp\/?attachment_id=126228#main\" rel=\"attachment wp-att-126228\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-126228\" alt=\"010\" src=\"http:\/\/www.flashfly.net\/wp\/wp-content\/uploads\/2015\/08\/010.jpg\" width=\"1024\" height=\"716\" \/><\/a><\/p>\n<p>\u0e07\u0e32\u0e19 \u201cMOBILE GAME FEST &amp; DIGITAL LIFESTYLE 2015\u201d \u0e08\u0e31\u0e14\u0e02\u0e36\u0e49\u0e19\u0e43\u0e19\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 21-23 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21\u0e19\u0e35\u0e49 \u0e13 \u0e23\u0e2d\u0e22\u0e31\u0e25 \u0e1e\u0e32\u0e23\u0e32\u0e01\u0e2d\u0e19 \u0e2e\u0e2d\u0e25\u0e25\u0e4c \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e40\u0e27\u0e25\u0e32 10.00 \u2013 20.00 \u0e19. \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19\u0e44\u0e1b\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19\u0e1f\u0e23\u0e35\u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e40\u0e2a\u0e35\u0e22\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48 <a href=\"http:\/\/www.mobilegamefest.com\" target=\"_blank\"><strong>www.mobilegamefest.com<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e23\u0e2d\u0e22\u0e31\u0e25 \u0e1e\u0e32\u0e23\u0e32\u0e01\u0e2d\u0e19\u0e2e\u0e2d\u0e25\u0e25\u0e4c \u0e1c\u0e19\u0e36\u0e01\u0e1e\u0e31\u0e19\u0e18\u0e21\u0e34\u0e15\u0e23\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 \u0e20\u0e32\u0e04\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e41\u0e25\u0e30\u0e04\u0e48\u0e32\u0e22\u0e40\u0e01\u0e21\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33<\/p>\n","protected":false},"author":1,"featured_media":126229,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"jnews_post_split":[]},"categories":[10270,7249],"tags":[19749,19988],"views":10,"_links":{"self":[{"href":"https:\/\/www.flashfly.net\/wp\/wp-json\/wp\/v2\/posts\/126226"}],"collection":[{"href":"https:\/\/www.flashfly.net\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.flashfly.net\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.flashfly.net\/wp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.flashfly.net\/wp\/wp-json\/wp\/v2\/comments?post=126226"}],"version-history":[{"count":0,"href":"https:\/\/www.flashfly.net\/wp\/wp-json\/wp\/v2\/posts\/126226\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.flashfly.net\/wp\/wp-json\/wp\/v2\/media\/126229"}],"wp:attachment":[{"href":"https:\/\/www.flashfly.net\/wp\/wp-json\/wp\/v2\/media?parent=126226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.flashfly.net\/wp\/wp-json\/wp\/v2\/categories?post=126226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.flashfly.net\/wp\/wp-json\/wp\/v2\/tags?post=126226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}